{"id":792,"count":4,"description":"","link":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/","name":"Keyword targeting","slug":"keyword-targeting-es","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.4 (Yoast SEO v19.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Keyword targeting Archives - ExoClick<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keyword targeting Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/\" \/>\n<meta property=\"og:site_name\" content=\"ExoClick\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exoclick.com\/wp-content\/uploads\/2018\/09\/ExoClick-1200x600.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/\",\"url\":\"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/\",\"name\":\"Keyword targeting Archives - ExoClick\",\"isPartOf\":{\"@id\":\"https:\/\/www.exoclick.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.exoclick.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Keyword targeting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.exoclick.com\/#website\",\"url\":\"https:\/\/www.exoclick.com\/\",\"name\":\"ExoClick\",\"description\":\"The innovative ad network\",\"publisher\":{\"@id\":\"https:\/\/www.exoclick.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.exoclick.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.exoclick.com\/#organization\",\"name\":\"ExoClick\",\"url\":\"https:\/\/www.exoclick.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.exoclick.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png\",\"contentUrl\":\"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png\",\"width\":1500,\"height\":613,\"caption\":\"ExoClick\"},\"image\":{\"@id\":\"https:\/\/www.exoclick.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Keyword targeting Archives - ExoClick","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/","og_locale":"es_ES","og_type":"article","og_title":"Keyword targeting Archives","og_url":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/","og_site_name":"ExoClick","og_image":[{"url":"https:\/\/www.exoclick.com\/wp-content\/uploads\/2018\/09\/ExoClick-1200x600.png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/","url":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/","name":"Keyword targeting Archives - ExoClick","isPartOf":{"@id":"https:\/\/www.exoclick.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"BreadcrumbList","@id":"https:\/\/www.exoclick.com\/es\/category\/keyword-targeting-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.exoclick.com\/es\/"},{"@type":"ListItem","position":2,"name":"Keyword targeting"}]},{"@type":"WebSite","@id":"https:\/\/www.exoclick.com\/#website","url":"https:\/\/www.exoclick.com\/","name":"ExoClick","description":"The innovative ad network","publisher":{"@id":"https:\/\/www.exoclick.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exoclick.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.exoclick.com\/#organization","name":"ExoClick","url":"https:\/\/www.exoclick.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.exoclick.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png","contentUrl":"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png","width":1500,"height":613,"caption":"ExoClick"},"image":{"@id":"https:\/\/www.exoclick.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.exoclick.com\/es\/wp-json\/wp\/v2\/categories\/792"}],"collection":[{"href":"https:\/\/www.exoclick.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.exoclick.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.exoclick.com\/es\/wp-json\/wp\/v2\/posts?categories=792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}