{"id":239,"count":72,"description":"","link":"https:\/\/www.exoclick.com\/de\/category\/video-de\/","name":"Video","slug":"video-de","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.4 (Yoast SEO v18.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.exoclick.com\/de\/category\/video-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video Archives - ExoClick\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.exoclick.com\/de\/category\/video-de\/\" \/>\n<meta property=\"og:site_name\" content=\"ExoClick\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.exoclick.com\/wp-content\/uploads\/2018\/09\/ExoClick-1200x600.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.exoclick.com\/#organization\",\"name\":\"ExoClick\",\"url\":\"https:\/\/www.exoclick.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.exoclick.com\/#logo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png\",\"contentUrl\":\"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png\",\"width\":1500,\"height\":613,\"caption\":\"ExoClick\"},\"image\":{\"@id\":\"https:\/\/www.exoclick.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.exoclick.com\/#website\",\"url\":\"https:\/\/www.exoclick.com\/\",\"name\":\"ExoClick\",\"description\":\"The innovative ad network\",\"publisher\":{\"@id\":\"https:\/\/www.exoclick.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.exoclick.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.exoclick.com\/de\/category\/video-de\/#webpage\",\"url\":\"https:\/\/www.exoclick.com\/de\/category\/video-de\/\",\"name\":\"Video Archives - ExoClick\",\"isPartOf\":{\"@id\":\"https:\/\/www.exoclick.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.exoclick.com\/de\/category\/video-de\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.exoclick.com\/de\/category\/video-de\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.exoclick.com\/de\/category\/video-de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.exoclick.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.exoclick.com\/de\/category\/video-de\/","og_locale":"de_DE","og_type":"article","og_title":"Video Archives - ExoClick","og_url":"https:\/\/www.exoclick.com\/de\/category\/video-de\/","og_site_name":"ExoClick","og_image":[{"url":"https:\/\/www.exoclick.com\/wp-content\/uploads\/2018\/09\/ExoClick-1200x600.png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.exoclick.com\/#organization","name":"ExoClick","url":"https:\/\/www.exoclick.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.exoclick.com\/#logo","inLanguage":"de-DE","url":"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png","contentUrl":"https:\/\/www.exoclick.com\/wp-content\/uploads\/2015\/04\/exoclick_new_baseline.png","width":1500,"height":613,"caption":"ExoClick"},"image":{"@id":"https:\/\/www.exoclick.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.exoclick.com\/#website","url":"https:\/\/www.exoclick.com\/","name":"ExoClick","description":"The innovative ad network","publisher":{"@id":"https:\/\/www.exoclick.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.exoclick.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"CollectionPage","@id":"https:\/\/www.exoclick.com\/de\/category\/video-de\/#webpage","url":"https:\/\/www.exoclick.com\/de\/category\/video-de\/","name":"Video Archives - ExoClick","isPartOf":{"@id":"https:\/\/www.exoclick.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.exoclick.com\/de\/category\/video-de\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.exoclick.com\/de\/category\/video-de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.exoclick.com\/de\/category\/video-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.exoclick.com\/de\/"},{"@type":"ListItem","position":2,"name":"Video"}]}]}},"_links":{"self":[{"href":"https:\/\/www.exoclick.com\/de\/wp-json\/wp\/v2\/categories\/239"}],"collection":[{"href":"https:\/\/www.exoclick.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.exoclick.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.exoclick.com\/de\/wp-json\/wp\/v2\/posts?categories=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}